{"id":19195,"date":"2025-05-10T18:22:27","date_gmt":"2025-05-10T18:22:27","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=19195"},"modified":"2025-05-10T18:22:27","modified_gmt":"2025-05-10T18:22:27","slug":"rina-sangrienta-en-zona-hotelera-de-cancun-1-muerto-y-20-detenidos","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2025\/05\/10\/rina-sangrienta-en-zona-hotelera-de-cancun-1-muerto-y-20-detenidos\/","title":{"rendered":"Ri\u00f1a sangrienta en zona Hotelera de Canc\u00fan: 1 Muerto y 20 detenidos."},"content":{"rendered":"<p>Ri\u00f1a sangrienta en zona Hotelera de Canc\u00fan: 1 Muerto y 20 detenidos.<\/p>\n<p style=\"text-align: center;\">\nBenito Ju\u00e1rez, Q. Roo,10 de Mayo del 2025.-La ma\u00f1ana de este s\u00e1bado se registr\u00f3 una violenta ri\u00f1a entre varias personas en aparente estado de ebriedad en los pasillos del kil\u00f3metro 9, en las inmediaciones del centro de convenciones. Testigos alertaron a la l\u00ednea de emergencias 911 sobre la pelea y reportaron tambi\u00e9n detonaciones de arma de fuego, dejando un saldo de una persona muerta y 20 detenidos.<\/p>\n<p>Elementos de la Polic\u00eda Tur\u00edstica acudieron al lugar y localizaron a un hombre sin signos vitales, tirado sobre el camell\u00f3n a un costado del centro de convenciones. El cuerpo presentaba visibles huellas de violencia. Al sitio tambi\u00e9n arribaron param\u00e9dicos de la empresa Life y del ERUM, quienes confirmaron que el masculino presuntamente de nacionalidad mexicana ya no contaba con vida.<\/p>\n<p>Gracias a una r\u00e1pida movilizaci\u00f3n, la Polic\u00eda Tur\u00edstica, en coordinaci\u00f3n con la Secretar\u00eda de Seguridad Ciudadana (SSC) y con apoyo de c\u00e1maras de videovigilancia, despleg\u00f3 un operativo que result\u00f3 en la detenci\u00f3n de aproximadamente 20 personas aparentemente involucradas en los hechos.<\/p>\n<p>El secretario de Seguridad Ciudadana y Tr\u00e1nsito de Benito Ju\u00e1rez Carlos Ernesto Damiano Sumuano se present\u00f3 en el lugar para supervisar las acciones policiales. Posteriormente, agentes de la Fiscal\u00eda General del Estado realizaron el levantamiento del cuerpo e iniciaron las investigaciones correspondientes.<\/p>\n<p>Los detenidos fueron puestos a disposici\u00f3n de la Fiscal\u00eda General del Estado, donde rendir\u00e1n su declaraci\u00f3n para determinar su grado de participaci\u00f3n en el violento altercado.<\/p>\n<p>En un principio se manej\u00f3 la versi\u00f3n de que la persona fallecida era un ex polic\u00eda municipal de Benito Ju\u00e1rez. Sin embargo, dicha informaci\u00f3n fue descartada luego de verificar sus datos en la plataforma M\u00e9xico, de acuerdo con fuentes oficiales.<\/p>\n<p>Las autoridades contin\u00faan con las investigaciones para esclarecer completamente los hechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ri\u00f1a sangrienta en zona Hotelera de Canc\u00fan: 1 Muerto y 20 detenidos. Benito Ju\u00e1rez, Q. Roo,10 de Mayo del 2025.-La ma\u00f1ana de este s\u00e1bado se registr\u00f3 una violenta ri\u00f1a entre &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2025\/05\/10\/rina-sangrienta-en-zona-hotelera-de-cancun-1-muerto-y-20-detenidos\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":19196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[15],"tags":[],"class_list":["post-19195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local-news","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2025\/05\/LogoLicious_20250510_131546.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19195"}],"version-history":[{"count":1,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19195\/revisions"}],"predecessor-version":[{"id":19197,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19195\/revisions\/19197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19196"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}