{"id":19506,"date":"2025-06-24T21:39:54","date_gmt":"2025-06-24T21:39:54","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=19506"},"modified":"2025-06-24T21:40:34","modified_gmt":"2025-06-24T21:40:34","slug":"19506","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2025\/06\/24\/19506\/","title":{"rendered":"S\u00faper arsenal y drogas decomisa en Juchit\u00e1n; podr\u00edan estar implicados autoridades con los delincuentes.!!"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>S\u00faper arsenal y drogas decomisa en Juchit\u00e1n; podr\u00edan estar implicados autoridades con los delincuentes.!!<\/p>\n<p>Sin decir palabras, por los hechos que vive Juchit\u00e1n de Zaragoza, el arsenal y dr!%^*( ga, decomisado a los municipales por fuerzas federales y estatales, el presidente municipal Miguel S\u00e1nchez Altamirano, se retiro del palacio de Gobierno.<\/p>\n<p>Informaci\u00f3n: Diego D\u00edaz<br \/>\nDurante el operativo \u201cJuchit\u00e1n Segura\u201d realizado el pasado fin de semana a los polic\u00edas municipales y C2, participaron un total de mil cuerpos de seguridad federal, estatal y se detuvo a dos personas.<\/p>\n<p>Durante el cateo, las fuerzas de seguridad incautaron ar!#%^ mas, chalecos anti!!# ba!#las y cientos de cartuchos de distintos calibres que no est\u00e1n registrados en el inventario oficial (LOC).<\/p>\n<p>Entre lo asegurado destacan:<br \/>\n\u2022 Colt y Pietro Veretta con cargadores abastecidos<br \/>\n\u2022Cargadores con sello de SEDENA<br \/>\n\u2022Chalecos antibalas sin documentaci\u00f3n<br \/>\n\u2022M\u00e1s de 100 cartuchos de uso militar (.45, 5.56, 7.62, 9 mm)<br \/>\n\u2022R\u00e9plicas de fusiles y armas de balines<\/p>\n<p>Adem\u00e1s, el centro de videovigilancia C2 fue clonado, lo que sugiere un control paralelo de la seguridad p\u00fablica por parte de grupos criminales.<\/p>\n<p>Por su parte el Fiscal General del Estado Bernardo Rodr\u00edguez Alamilla afirm\u00f3 que \u201cPor parte del Estado hay toda intenci\u00f3n de buscar y de detener a esta persona (Comandante Cromo) y todos aquellos generadores de violencia\u201d en Juchit\u00e1n.<\/p>\n<p>Asever\u00f3 que tienen la obligaci\u00f3n de detenerlos, \u201cel aparato del estado no est\u00e1 encubriendo absolutamente a nadie\u201d dijo Alamilla.<\/p>\n<p>Aunque descart\u00f3 los presuntos se\u00f1alamientos de servidores p\u00fablicos con c\u00e9lulas delictivas de Juchit\u00e1n de Zaragoza, descart\u00f3 estas acusaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; S\u00faper arsenal y drogas decomisa en Juchit\u00e1n; podr\u00edan estar implicados autoridades con los delincuentes.!! Sin decir palabras, por los hechos que vive Juchit\u00e1n de Zaragoza, el arsenal y dr!%^*( &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2025\/06\/24\/19506\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":19507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[40],"tags":[],"class_list":["post-19506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2025\/06\/LogoLicious_20250624_153730.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19506"}],"version-history":[{"count":2,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19506\/revisions"}],"predecessor-version":[{"id":19509,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19506\/revisions\/19509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19507"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}