{"id":19526,"date":"2025-07-03T15:46:41","date_gmt":"2025-07-03T15:46:41","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=19526"},"modified":"2025-07-03T15:46:41","modified_gmt":"2025-07-03T15:46:41","slug":"preocupante-el-nivel-de-la-laguna-de-tres-palos-lugarenos","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2025\/07\/03\/preocupante-el-nivel-de-la-laguna-de-tres-palos-lugarenos\/","title":{"rendered":"Preocupante el nivel de la laguna de tres palos; lugare\u00f1os."},"content":{"rendered":"<p>Preocupante el nivel de la laguna de tres palos; lugare\u00f1os.<\/p>\n<p>H\u00e9ctor Brise\u00f1o, corresponsal<\/p>\n<p>Acapulco, Gro. Lugare\u00f1os toman previsiones ante la posible presencia de mar de fondo en la playa de Barra Vieja. Sin embargo, lo que m\u00e1s preocupa a los pobladores es el crecimiento del nivel de la laguna de Tres Palos, que tiene su desembocadura en la Barra Vieja.<\/p>\n<p>&#8220;Ya le falta poco para que la abran, ya creci\u00f3 bastante la laguna, as\u00ed como yo lo veo otra lluvia fuerte y ya&#8221;, expres\u00f3 un estudiante que caminaba por el puente de la carretera Barra Vieja-Lomas de Chapultepec, desde donde se observan los trabajos manuales para tener lista la apertura de la barra cuando sea necesario.<\/p>\n<p>&#8220;Aqu\u00ed no queremos otro hurac\u00e1n&#8221;, dice uno de sus compa\u00f1eros cuando se le pregunta si se necesita la fuerza de un hurac\u00e1n para que la barra sea abierta.<\/p>\n<p>Si bien las olas no han afectado por ahora el \u00e1rea de restaurantes de la playa, el color del mar s\u00ed, pues en los \u00faltimos d\u00edas adquiri\u00f3 tonos caf\u00e9 y chocolatosos, debido al mar revuelto, lo cual ahuyenta a turistas y familias que buscan descansar y tomar fotograf\u00edas del lugar.<\/p>\n<p>Autoridades de los tres niveles de gobierno mantienen bajo supervisi\u00f3n permanente el nivel de la laguna de Tres Palos, especialmente desde principios de junio, con el objetivo de prevenir incidentes ante las lluvias que se han registrado en Acapulco.<\/p>\n<p>Desde el pasado 27 de junio, personal de protecci\u00f3n civil municipal realiz\u00f3 trabajos preparativos en Barra Vieja.<\/p>\n<p>El coordinador General de Protecci\u00f3n Civil y Bomberos de Acapulco, Ra\u00fal Noyola Rocha, explic\u00f3 que realizaron trabajos para mantener preparada la barra, para en caso de subir los niveles del agua, pueda abrirse y as\u00ed evitar inundaciones.<\/p>\n<p>Para ello fueron ocupadas dos m\u00e1quinas retroexcavadoras, con la participaci\u00f3n de prestadores de servicios, pescadores y pobladores de Barra Vieja.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preocupante el nivel de la laguna de tres palos; lugare\u00f1os. H\u00e9ctor Brise\u00f1o, corresponsal Acapulco, Gro. Lugare\u00f1os toman previsiones ante la posible presencia de mar de fondo en la playa de &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2025\/07\/03\/preocupante-el-nivel-de-la-laguna-de-tres-palos-lugarenos\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":19527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[15],"tags":[],"class_list":["post-19526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local-news","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2025\/07\/LogoLicious_20250703_094523.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19526"}],"version-history":[{"count":1,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19526\/revisions"}],"predecessor-version":[{"id":19528,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19526\/revisions\/19528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19527"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}