{"id":19625,"date":"2025-09-07T21:16:23","date_gmt":"2025-09-07T21:16:23","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=19625"},"modified":"2025-09-07T21:16:23","modified_gmt":"2025-09-07T21:16:23","slug":"aseguran-mansion-helicoptero-autos-de-lujo-y-arsenal-a-empresario-ligado-a-celula-criminal-de-la-barredora","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2025\/09\/07\/aseguran-mansion-helicoptero-autos-de-lujo-y-arsenal-a-empresario-ligado-a-celula-criminal-de-la-barredora\/","title":{"rendered":"Aseguran mansi\u00f3n, helic\u00f3ptero, autos de lujo y arsenal a empresario ligado a c\u00e9lula criminal de \u201cLa Barredora\u201d."},"content":{"rendered":"<p style=\"padding-left: 40px;\">Aseguran mansi\u00f3n, helic\u00f3ptero, autos de lujo y arsenal a empresario ligado a c\u00e9lula criminal de \u201cLa Barredora\u201d.<\/p>\n<p>*El empresario es \u00edntimo amigo de AMLO y del ex gobernador y senador morenista Ad\u00e1n Augusto L\u00f3pez.<\/p>\n<p>Villahermosa, Tabasco, 7 de septiembre de 2025. \u2014 En un operativo encabezado por la Fuerza Institucional Regional Tabasco Olmeca (FIRTOlmeca), autoridades aseguraron una lujosa residencia ubicada en la rancher\u00eda Traconis, a escasos minutos del aeropuerto de la capital tabasque\u00f1a.<\/p>\n<p>El despliegue policial permiti\u00f3 el decomiso de bienes millonarios, armamento de alto poder y fauna ex\u00f3tica, lo que puso al descubierto el nivel de ostentaci\u00f3n y presunta protecci\u00f3n criminal con la que operaba el inmueble.<\/p>\n<p>Bienes asegurados<\/p>\n<p>Dentro de la propiedad se incaut\u00f3 un helic\u00f3ptero, varios veh\u00edculos de lujo \u2014entre ellos un Porsche\u2014, as\u00ed como un arsenal compuesto por armas de asalto y cartuchos de diversos calibres.<\/p>\n<p>La sorpresa mayor fue el hallazgo de un zool\u00f3gico clandestino: una cebra, un avestruz, tortugas gigantes y aves ex\u00f3ticas, entre ellas seis guacamayas de cabeza azul, cuatro de cabeza verde y tres loros de cabeza amarilla.<\/p>\n<p>Investigaciones en curso<\/p>\n<p>Aunque no se reportaron personas detenidas, las autoridades confirmaron que la mansi\u00f3n pertenece al empresario chiapaneco Mario \u201cN\u201d, actualmente investigado por sus presuntos v\u00ednculos con el grupo delictivo conocido como La Barredora.<\/p>\n<p>Fuentes de seguridad indicaron que este golpe forma parte de una estrategia regional para debilitar las estructuras financieras y log\u00edsticas de dicho c\u00e1rtel, que en los \u00faltimos meses ha extendido su influencia hacia la zona del sureste mexicano.<\/p>\n<p>Contexto<\/p>\n<p>El aseguramiento se suma a las recientes acciones de inteligencia que han derivado en cateos y decomisos en propiedades ligadas a personajes del \u00e1mbito empresarial y pol\u00edtico con nexos en el crimen organizado.<\/p>\n<p>Las autoridades locales y federales mantienen hermetismo sobre los pr\u00f3ximos pasos, pero no se descarta que en las pr\u00f3ximas horas se emitan \u00f3rdenes de aprehensi\u00f3n en contra del empresario y sus presuntos socios.<\/p>\n<p>Qu\u00e9 va a hacer menci\u00f3n, que dicho empresario es \u00edntimo amigo del ex gobernador y actual senador Ad\u00e1n Augusto L\u00f3pez primo hermano del expresidente Andr\u00e9s Manuel L\u00f3pez Obrador<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aseguran mansi\u00f3n, helic\u00f3ptero, autos de lujo y arsenal a empresario ligado a c\u00e9lula criminal de \u201cLa Barredora\u201d. *El empresario es \u00edntimo amigo de AMLO y del ex gobernador y senador &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2025\/09\/07\/aseguran-mansion-helicoptero-autos-de-lujo-y-arsenal-a-empresario-ligado-a-celula-criminal-de-la-barredora\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":19626,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[15],"tags":[],"class_list":["post-19625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local-news","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2025\/09\/LogoLicious_20250907_151103.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19625"}],"version-history":[{"count":1,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19625\/revisions"}],"predecessor-version":[{"id":19627,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19625\/revisions\/19627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19626"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}