{"id":19744,"date":"2026-01-19T01:16:02","date_gmt":"2026-01-19T01:16:02","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=19744"},"modified":"2026-01-19T01:16:02","modified_gmt":"2026-01-19T01:16:02","slug":"persecucion-y-balacera-de-sicarios-en-zihuatanejo","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2026\/01\/19\/persecucion-y-balacera-de-sicarios-en-zihuatanejo\/","title":{"rendered":"Persecuci\u00f3n y balacera de sicarios en Zihuatanejo!!"},"content":{"rendered":"<p>Persecuci\u00f3n y balacera de sicarios en Zihuatanejo!!<\/p>\n<p>*Tras la persecuci\u00f3n queda un hombre lesionado por los gatilleros<\/p>\n<p>Zihuatanejo, Gro; 18 de enero de 2026.- Un hombre fue herido a balazos<\/p>\n<hr \/>\n<p>en la colonia La Noria, en este puerto de Zihuatanejo, tras haber sido perseguido por los sicarios.<\/p>\n<p>Los hechos de sangre se registraron a las 13:45 horas de la tarde de este domingo, donde llegaron autoridades de los tres niveles de gobierno para acordonar la zona.<\/p>\n<p>El herido de bala fue trasladado por rescatistas de la Cruz Roja al hospital, cuyo estado de salud fue reportado como sumamente grave.<\/p>\n<p>En la escena del crimen fueron hallados varios casquillos de arma corta que quedaron a disposici\u00f3n de las autoridades ministeriales.<\/p>\n<p>El agente auxiliar del Ministerio P\u00fablico y peritos de la Fiscal\u00eda General del Estado se encargaron de realizar las diligencias de ley.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Persecuci\u00f3n y balacera de sicarios en Zihuatanejo!! *Tras la persecuci\u00f3n queda un hombre lesionado por los gatilleros Zihuatanejo, Gro; 18 de enero de 2026.- Un hombre fue herido a balazos &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2026\/01\/19\/persecucion-y-balacera-de-sicarios-en-zihuatanejo\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":19745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[15],"tags":[],"class_list":["post-19744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local-news","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2026\/01\/IMG-20260118-WA0013.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19744"}],"version-history":[{"count":1,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19744\/revisions"}],"predecessor-version":[{"id":19746,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19744\/revisions\/19746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19745"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}