{"id":3095,"date":"2020-07-24T21:22:44","date_gmt":"2020-07-24T21:22:44","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=3095"},"modified":"2020-07-24T21:22:44","modified_gmt":"2020-07-24T21:22:44","slug":"lozoya-revela-pagos-de-odebrecht-para-campana-de-pena-sobornos-a-anaya-y-panistas","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2020\/07\/24\/lozoya-revela-pagos-de-odebrecht-para-campana-de-pena-sobornos-a-anaya-y-panistas\/","title":{"rendered":"Lozoya revela pagos de Odebrecht para campa\u00f1a de Pe\u00f1a, sobornos a Anaya y panistas."},"content":{"rendered":"\n<p>Lozoya revela pagos de Odebrecht para campa\u00f1a de Pe\u00f1a, sobornos a Anaya y panistas.<\/p>\n\n\n\n<p>CIUDAD DE M\u00c9XICO (apro).- #EmilioLozoya revel\u00f3 que la empresa brasile\u00f1a Odebrecht pag\u00f3 cuatro millones de d\u00f3lares que fueron usados para la campa\u00f1a presidencial de #EnriquePe\u00f1aNieto, en 2012, en especifico para el pago de a consultores extranjeros en materia electoral contrataos por el entonces coordinador de la campa\u00f1a, #LuisVidegaray.<br>Asimismo, seg\u00fan publica hoy el diario #Reforma, el exdirector de #Pemex, quien es testigo protegido del gobierno actual, inform\u00f3 que pag\u00f3 sobornos por un monto de 52 millones 380 mil pesos a legisladores del #PAN para que aprobaran las reformas del Pacto por M\u00e9xico.<br>De ese monto, seg\u00fan Lozoya, 6.8 millones fueron para #RicardoAnaya, quien era presidente de la C\u00e1mara de diputados cuando se discuti\u00f3 la reforma energ\u00e9tica, del 2013 a marzo de 2014.<br>Poco despu\u00e9s, en mayo, Anaya asumi\u00f3 la dirigencia nacional del PAN, desde donde empez\u00f3 a tejer su candidatura presidencial.<br>Ambas revelaciones forman parte del documento que #Proceso public\u00f3 como primicia sobre la primera declaraci\u00f3n firmada de Lozoya.<br>De acuerdo con la informaci\u00f3n proporcionada por Lozoya al gobierno actual, en el caso de los pagos de #Odebrecht, ya cuando Pe\u00f1a Nieto era presidente, la empresa brasile\u00f1a desembols\u00f3 seis millones de d\u00f3lares para beneficiarse con contratos y para que dispusiera de una parte para sobornar a los legisladores y garantizar la aprobaci\u00f3n de la reforma energ\u00e9tica en 2014,<br>El enlace designado por la presidencia era el priista #DavidPenchyna, entonces presidente de la Comisi\u00f3n de Energ\u00eda del Senado.<br>Incluso di\u00f3 detalles de donde se pact\u00f3 uno de los pagos de Odebrecht.<br>Lozoya narr\u00f3 que por instrucciones de Videgaray, acudi\u00f3 a entrevistarse con #LuisAlbertoMenesesWeylli, entonces director de Odebrecht en M\u00e9xico, en la panader\u00eda El Globo de Prado Sur, en las Lomas de Chapultepec.<br>Ah\u00ed, Meneses Weylli se habr\u00eda comprometido a entregar cuatro millones de d\u00f3lares, de los cuales deposit\u00f3 tres millones 150 mil d\u00f3lares en la off shore Latin America Asia Capital Holding LTD, cuenta vinculada con Lozoya en la investigaci\u00f3n que lleva a cabo la Fiscal\u00eda General de la Rep\u00fablica (FGR) en el caso Odebrecht.<\/p>\n\n\n\n<p>Seg\u00fan Lozoya, inform\u00f3 de ese movimiento inform\u00f3 a Videgaray y al propio Pe\u00f1a Nieto.<\/p>\n\n\n\n<p>En caso Lozoya deben comparecer todos los involucrados, incluidos expresidentes: #AMLO<\/p>\n\n\n\n<p>PAN: Quien acusa est\u00e1 obligado a probar; hasta el momento, los de Lozoya, solo son dicho.<\/p>\n\n\n\n<p>Los sobornos a los panistas<br>los legisladores, Lozoya revel\u00f3 que por medio de terceros entreg\u00f3 52 millones 380 mil pesos a legisladores panistas, 6.8 millones de esos a #RicardoAnaya el 8 de agosto de 2014 a trav\u00e9s de una persona no identificada, aunque Lozoya dijo tener dos n\u00fameros telef\u00f3nicos con los que se usaron para concretar la entrega.<br>Adem\u00e1s de Anaya, en los sobornos estar\u00edan involucrados #ErnestoCordero, ex coordinador de la bancada del #PAN, y los hoy gobernadores de #Quer\u00e9taro, #FranciscoDom\u00ednguez, y de #Tamaulipas, #FranciscoGarc\u00edaCabezadeVaca, as\u00ed como el senador Jos\u00e9 Luis Lavalle Maury.<br>\u201cLozoya tuvo dinero para comprar y se reparti\u00f3 dinero a legisladores de partidos, ser\u00eda muy importante terminar de saber \u00bfcu\u00e1nto? porque otro asunto es este manejo ilegal, lo que se utiliz\u00f3 para comprar, sobornar a legisladores y se aprobara la reforma energ\u00e9tica, en el llamado Pacto por M\u00e9xico donde sin duda se us\u00f3 dinero con ese prop\u00f3sito y resulto ser Pacto contra M\u00e9xico\u201d. expres\u00f3 el tabasque\u00f1o.<br>L\u00f3pez Obrador subray\u00f3 que es un asunto que amerita que se atienda a fondo, que se terminen las declaraciones y se busque un modo, sin violar el debido proceso, de informar para que la gente conozca toda la verdad. \u201cLa transparencia es una regla de oro y los mexicanos deben saber qu\u00e9 sucedi\u00f3 con ese asunto y se llame a declarar a todos los implicados\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lozoya revela pagos de Odebrecht para campa\u00f1a de Pe\u00f1a, sobornos a Anaya y panistas. CIUDAD DE M\u00c9XICO (apro).- #EmilioLozoya revel\u00f3 que la empresa brasile\u00f1a Odebrecht pag\u00f3 cuatro millones de d\u00f3lares &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2020\/07\/24\/lozoya-revela-pagos-de-odebrecht-para-campana-de-pena-sobornos-a-anaya-y-panistas\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":3096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[40],"tags":[],"class_list":["post-3095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2020\/07\/LogoLicious_20200724_161202.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3095"}],"version-history":[{"count":1,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3095\/revisions"}],"predecessor-version":[{"id":3097,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/3095\/revisions\/3097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/3096"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}