{"id":5159,"date":"2020-10-05T02:54:13","date_gmt":"2020-10-05T02:54:13","guid":{"rendered":"https:\/\/unoticias.com.mx\/?p=5159"},"modified":"2020-10-05T02:54:13","modified_gmt":"2020-10-05T02:54:13","slug":"se-burlo-de-deportistas-de-chilpancingo-dono-pedacera-de-tableros","status":"publish","type":"post","link":"https:\/\/unoticias.com.mx\/index.php\/2020\/10\/05\/se-burlo-de-deportistas-de-chilpancingo-dono-pedacera-de-tableros\/","title":{"rendered":"SE BURL\u00d3 DE DEPORTISTAS DE CHILPANCINGO DON\u00d3 PEDACERA DE TABLEROS."},"content":{"rendered":"\n<p>SE BURL\u00d3 DE DEPORTISTAS DE CHILPANCINGO DON\u00d3 PEDACERA DE TABLEROS.<\/p>\n\n\n\n<p>Por: Amado Bautista Soriano.<\/p>\n\n\n\n<p>CHILPANCINGO.- Habitantes de la colonia Bugambilias de esta ciudad capital, nos solicitaron hacer p\u00fablico su descontento por lo que a ellos, les pareci\u00f3 un verdadera burla la que les hizo Fernando Fernando Calixto Cuevas y es que en una pl\u00e1tica sostenida con el coordinador de gabinete del ayuntamiento de Chilpancingo, \u00e9ste se comprometi\u00f3 a apoyarlos con la donaci\u00f3n de los dos tableros de la cancha de basquetbol que se ubica precisamente en la entrada de la misma colonia.<br>A decir de los quejosos, ya no hab\u00edan querido acercarse al gobierno municipal porque han tenido la mala experiencia de que en todas las administraciones pasadas, desde hace m\u00e1s de 20 a\u00f1os, los han desilusionado con las promesas de ayuda pero como sucede siempre en estos casos, solo les dan falsas esperanzas, por lo que hastiados por estas desagradables costumbres, optaron mejor por ya no pedirle nada al gobierno. Sin embargo, en un encuentro con Calixto D\u00edaz, despu\u00e9s de hablarles bonito, dici\u00e9ndoles que ellos eran \u201csu gente\u201d y que no solo es tambi\u00e9n vecino cercano de la colonia, y que incluso de chamaco \u00e9l iba a jugar a esa cancha y que le tra\u00eda especial recuerdo de su juventud, les dijo que no se preocuparan m\u00e1s y se comprometi\u00f3 a otorgarles los dos tableros de la cancha de b\u00e1squetbol, por lo que los ingenuos vecinos, cayeron redonditos una vez, ante las \u201ctiernas y suaves\u201d palabras de Fernando Calixto.Y efectivamente les cumpli\u00f3, pero cu\u00e1l fue grande la sorpresa que se llevaron los vecinos de la colonia bugambilias al recibir los dos tableros pero m\u00e1s que de basquetbol parec\u00edan portezuelas de auto despu\u00e9s de un choque, puesto que Calixto Cuevas, les dio los tableros, \u00a1pero todos chuecos! Con el aro de la canasta aplastado, inservible, ni repararlos ser\u00e1 posible. Hasta verg\u00fcenza sintieron de mostrarselos. Listos para ser tirados en la basura por lo que sin duda alguna, si fue una verdadera burla, la que el funcionario les hizo, \u201cmejor no se las hubiera dado\u201d, dijeron en tono triste y desilusionado los vecinos, que aseguran esta vez \u201cYa nunca m\u00e1s volveremos a creer en las promesas de los malos servidores p\u00fablicos\u201d. Y ojala aprenda, porque para nadie es desconocido la manera de trabajar de la mayor\u00eda de los que se suponen son servidores p\u00fablicos.<br>Ante este hecho, ya se re\u00fanen los vecinos y comit\u00e9 de la colonia Bugambilias, para realizar actividades conjuntas que les permitan reunir fondos econ\u00f3micos y a trav\u00e9s de cooperaciones propias para comprar los tableros, y no solo eso, tambi\u00e9n darle mantenimiento y adquirir luminarias para la cancha puesto que es el \u00fanico entretenimiento que tienen j\u00f3venes y adultos de esa unidad habitacional y que por las noches, tienen que jugar en la plena oscuridad, tal como lo demuestran las im\u00e1genes que aqu\u00ed proporcionamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SE BURL\u00d3 DE DEPORTISTAS DE CHILPANCINGO DON\u00d3 PEDACERA DE TABLEROS. Por: Amado Bautista Soriano. CHILPANCINGO.- Habitantes de la colonia Bugambilias de esta ciudad capital, nos solicitaron hacer p\u00fablico su descontento &hellip; <a href=\"https:\/\/unoticias.com.mx\/index.php\/2020\/10\/05\/se-burlo-de-deportistas-de-chilpancingo-dono-pedacera-de-tableros\/\" class=\"more-link\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":5160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[15],"tags":[],"class_list":["post-5159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local-news","entry"],"jetpack_featured_media_url":"https:\/\/unoticias.com.mx\/wp-content\/uploads\/2020\/10\/FB_IMG_1601866179287.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5159"}],"version-history":[{"count":1,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5159\/revisions"}],"predecessor-version":[{"id":5161,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5159\/revisions\/5161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5160"}],"wp:attachment":[{"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unoticias.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}